{"id":40707,"date":"2025-07-31T10:04:26","date_gmt":"2025-07-31T10:04:26","guid":{"rendered":"https:\/\/www.pegasuscadcam.com\/?post_type=case-history&#038;p=40707"},"modified":"2025-07-31T10:04:26","modified_gmt":"2025-07-31T10:04:26","slug":"metalworks","status":"publish","type":"case-history","link":"https:\/\/pegasuscadcam.com\/es\/case_history\/metalworks\/","title":{"rendered":"Metalworks"},"content":{"rendered":"<h2><strong>Innovaci\u00f3n en la creaci\u00f3n de prototipos de accesorios de moda gracias a Pegasus CAD-CAM.<\/strong><\/h2>\n<p>Metalworks S.p.A. es un referente en Italia en el dise\u00f1o y producci\u00f3n de accesorios de moda en zamak y materiales pl\u00e1sticos. La empresa se destaca por su capacidad para transformar las ideas de los clientes en productos terminados, combinando la artesan\u00eda italiana con tecnolog\u00edas avanzadas, para ofrecer soluciones elegantes, funcionales y sostenibles.<\/p>\n<p>En un mercado en constante evoluci\u00f3n, la rapidez en la producci\u00f3n de muestras se ha convertido en una prioridad. Metalworks decidi\u00f3 ampliar sus capacidades internas apostando por la <b>creaci\u00f3n r\u00e1pida de prototipos y la producci\u00f3n de peque\u00f1as series en lat\u00f3n con bajo contenido de plomo<\/b>.<\/p>\n<p>El principal desaf\u00edo era identificar un <b>software CAD-CAM<\/b> capaz de:<\/p>\n<ul>\n<li>Comunicarse con diferentes m\u00e1quinas herramienta<\/li>\n<li>Optimizar los tiempos de programaci\u00f3n<\/li>\n<li>Mantener altos est\u00e1ndares de calidad incluso en mecanizados complejos<\/li>\n<\/ul>\n<p>Tras una evaluaci\u00f3n cuidadosa, se eligi\u00f3 el software <b>Pegasus CAD-CAM<\/b>, inicialmente instalado en una m\u00e1quina Cielle y posteriormente integrado con una Doosan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pegasus CAD-CAM al servicio de la creatividad: innovaci\u00f3n y precisi\u00f3n en la creaci\u00f3n de prototipos de accesorios de moda made in Italy. <\/p>\n","protected":false},"featured_media":40611,"template":"","categories":[14],"class_list":["post-40707","case-history","type-case-history","status-publish","has-post-thumbnail","hentry","category-mech"],"acf":[],"_links":{"self":[{"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/case-history\/40707"}],"collection":[{"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/case-history"}],"about":[{"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/types\/case-history"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/media\/40611"}],"wp:attachment":[{"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/media?parent=40707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pegasuscadcam.com\/es\/wp-json\/wp\/v2\/categories?post=40707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}